

{"id":2542,"count":1,"description":"","link":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/","name":"Koalitionsstreit","slug":"koalitionsstreit","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Koalitionsstreit Archive - starke-meinungen.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Koalitionsstreit Archive - starke-meinungen.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/\" \/>\n<meta property=\"og:site_name\" content=\"starke-meinungen.de\" \/>\n<meta property=\"og:image\" content=\"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@starkemeinungen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/tag\\\/koalitionsstreit\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/tag\\\/koalitionsstreit\\\/\",\"name\":\"Koalitionsstreit Archive - starke-meinungen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/tag\\\/koalitionsstreit\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/tag\\\/koalitionsstreit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Koalitionsstreit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"name\":\"starke-meinungen.de\",\"description\":\"Autoren-Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\",\"name\":\"starke-meinungen.de\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"contentUrl\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"width\":1200,\"height\":630,\"caption\":\"starke-meinungen.de\"},\"image\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/starkemeinungen\\\/\",\"https:\\\/\\\/x.com\\\/starkemeinungen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Koalitionsstreit Archive - starke-meinungen.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/","og_locale":"de_DE","og_type":"article","og_title":"Koalitionsstreit Archive - starke-meinungen.de","og_url":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/","og_site_name":"starke-meinungen.de","og_image":[{"width":1200,"height":630,"url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@starkemeinungen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/","url":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/","name":"Koalitionsstreit Archive - starke-meinungen.de","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/starke-meinungen.de\/blog\/tag\/koalitionsstreit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/starke-meinungen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Koalitionsstreit"}]},{"@type":"WebSite","@id":"https:\/\/starke-meinungen.de\/blog\/#website","url":"https:\/\/starke-meinungen.de\/blog\/","name":"starke-meinungen.de","description":"Autoren-Blog","publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/starke-meinungen.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/starke-meinungen.de\/blog\/#organization","name":"starke-meinungen.de","url":"https:\/\/starke-meinungen.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","contentUrl":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","width":1200,"height":630,"caption":"starke-meinungen.de"},"image":{"@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/starkemeinungen\/","https:\/\/x.com\/starkemeinungen"]}]}},"_links":{"self":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/tags\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts?tags=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}