

{"id":3871,"date":"2013-04-23T00:52:09","date_gmt":"2013-04-22T23:52:09","guid":{"rendered":"https:\/\/starke-meinungen.de\/blog\/?p=3871"},"modified":"2013-04-22T08:54:14","modified_gmt":"2013-04-22T07:54:14","slug":"neulich-in-kreuzberg","status":"publish","type":"post","link":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/","title":{"rendered":"Neulich in Kreuzberg"},"content":{"rendered":"<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Wie die meisten Gro\u00dfstadtbewohner kenne ich meine Stadt nicht wirklich. Mein allt\u00e4gliches Leben spielt sich ab zwischen meinem Wohnquartier im gutb\u00fcrgerlichen S\u00fcdwesten der Stadt, meinem Arbeitsplatz an der Grenze Kreuzberg und Mitte, der Wohnung meiner Tochter in der N\u00e4he des Kottbusser Tors in Kreuzberg, und den diversen Kinos, Museen, Galerien, Caf\u00e9s und Restaurants, haupts\u00e4chlich in Charlottenburg, Mitte und Kreuzberg, in denen ich einen Teil meiner Freizeit verbringe. (Und nat\u00fcrlich dem Gartencenter um die Ecke.) <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Selten verirre ich mich in Neubau-Bezirke wie Marzahn oder Hellersdorf im Osten; in die Gropiusstadt oder das M\u00e4rkische Viertel im Westen. <!--more-->Andere Bezirke, wie etwa Spandau und Reinickendorf, kenne ich von fr\u00fcher, weil ich dort zur Schule ging oder als Lehrer in die Schule; aber ich bin nur noch selten dort. Und dann gibt\u2019s den Prenzlauer Berg und Friedrichshain, wo ich mich wie ein Tourist in einer fremden Stadt \u2013 nein in einer fremden Welt \u2013 bewege. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Neulich \u00fcberkam mich allerdings dieses Gef\u00fchl der Fremdheit mitten in Kreuzberg, einem Bezirk, das ich seit Jahrzehnten kenne und liebe. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Hier \u2013 im Studio Naunynstra\u00dfe \u2013 habe ich als Sch\u00fcler anno 1968 einen M\u00f6chtegern-Avantgardefilm gedreht. Hier \u2013 in \u00fcberf\u00fcllten und verrauchten Hinterhofkinos \u2013 habe ich die Filme von Andy Warhol gesehen. Hier \u2013 in der Katzbachstra\u00dfe \u2013 habe ich als Student anno 1970 mit Freunden eine Wohngemeinschaft gegr\u00fcndet. Hier habe ich als Kommunist Kampagnen gef\u00fchrt \u2013 1975 etwa f\u00fcr eine Kinderklinik im stillgelegten Bethanien-Krankenhaus, zu dessen Besetzung wir aufriefen, und das heute ein K\u00fcnstlerhaus ist. Bei einer dieser Demonstrationen bekam ich \u2013 in der Adalbertstra\u00dfe \u2013 einen Polizeikn\u00fcppel \u00fcber den Kopf, die Wunde wurde hier \u2013 im Urbankrankenhaus \u2013 gen\u00e4ht, ohne Bet\u00e4ubung, weil der Arzt Sympathisant der SEW war und uns \u201eAnuller\u201c f\u00fcr Konterrevolution\u00e4re hielt. Hier wurden Anfang der 1980er Jahre die ersten H\u00e4user besetzt. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Das Anliegen der Besetzer \u2013 Stopp der Entmietung und des Abrisses \u2013 habe ich als Lehrer finanziell unterst\u00fctzt; mit Hart-Walter H\u00e4mer und seinem Konzept der \u201ebehutsamen Stadterneuerung\u201c wurde es nach einiger Zeit, vielen R\u00e4umungen und einem Todesopfer zur offiziellen Politik des Bezirks und der Stadt. Mit H\u00e4mer und meinem Vater habe ich die damals neuen Vorzeigeh\u00e4user des Ehepaars Hinrich und Inken Baller am Urban-Hafen besucht. Auf dem Kreuzberg haben Maria und ich noch jedes Jahr Silvester gefeiert, als wir l\u00e4ngst in Zehlendorf wohnten, und das Volksfest auf dem Kreuzberg besuche ich noch heute gern.\u00a0 Hier \u2013 in der K\u00f6penicker Stra\u00dfe \u2013 hatte Mitte der 1980er Jahren die \u201eBerlin Blues Band\u201c, deren S\u00e4nger ich war, ihren \u00dcbungsraum, zusammen mit einer NDW-Gruppe namens \u201eIdeal\u201c. Hier \u2013 im \u201eGolgatha\u201c, im Haus am B\u00f6cklerpark, in der \u201eVilla Kreuzberg\u201c und auf Kiezfesten in der Graefestra\u00dfe \u2013 bin ich mit der Blues Band und anderen Formationen aufgetreten. Hierher bin ich seit Jahrzehnten immer wieder gekommen, um englischsprachige Filme im \u201eBabylon\u201c-Kino zu gucken, die \u201eGorillas\u201c im Ratibor-Theater oder das Kabarett \u201eZwei Drittel\u201c im Mehringhof zu sehen, wo auch \u201ePillepalle und die \u00d6tterp\u00f6tter\u201c spielten, mit meinem Ex-Genossen und Freund Jochen Staadt am\u00a0 Schlagzeug; oder um an lauen Sommerabenden Fu\u00dfball in den Kneipeng\u00e4rten am Schlesischen Tor zu gucken. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Dort trauerte ich anno 2006 mit dem ganzen Bezirk, als Zinedine Zidane im Endspiel gegen Italien nach seinem Kopfsto\u00df gegen den nichtsw\u00fcrdigen Matterazzi vom Platz gewiesen wurde. In Kreuzberg haben Freunde von mir als Lehrer gearbeitet und gegen alle Widrigkeiten das Konzept multikultureller und toleranter\u00a0 Erziehung verteidigt. Hier ging ich mit dem\u00a0 Gr\u00fcnen-Politiker \u00d6zcan Mutlu auf den Spuren des angeblich aus dem Bezirk verjagten Thilo Sarrazin spazieren und traf nur freundliche Menschen, vom t\u00fcrkischen Gem\u00fcseh\u00e4ndler bis zum Gemeindevorsteher der Alewiten. Hier hat sich der Sohn israelischer Freunde eine Wohnung gekauft, die er an Touristen vermietet, hier gibt es ein Caf\u00e9, wo sich Israelis gern treffen und wohl f\u00fchlen. Hier wohnen alte Freunde, hier wohnt, wie gesagt, meine Tochter mit Mann und Kind. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Kreuzberg ist eigentlich mein Berlin. Mein Ideal von Berlin.<\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Und doch geschah es gerade im Bergmann-Kiez, wo meine Tochter vor zwei Jahren ihre erste Fotoausstellung hatte, dass mich pl\u00f6tzlich ein Gef\u00fchl der Fremdheit ankam, wie ich es sonst nur vom Prenzlauer Berg oder von Friedrichshain kenne, und aus den gleichen Gr\u00fcnden. Ich war unterwegs, um ein paar Filme aus dem \u201eVideodrom\u201c zu holen, wo die Videos nach Genre (nicht blo\u00df \u201eKrimi\u201c, sondern z.B. \u201eGood Cop \u2013 Bad Cop\u201c; nicht blo\u00df \u201eHistoriendrama\u201c, sondern \u201eitalienische Sandalenfilme\u201c usw.) und dann wieder nach Regisseur sortiert sind, und wo man sicher sein kann, nicht nur einen seltenen und von der Kritik verrissenen Film wie \u2013 sagen wir \u2013 \u201eVillain\u201c mit Richard Burton zu bekommen, sondern dazu den Kommentar des sachkundigen Personals: \u201eBurtons Frisur ist echt zum Schreien. Und dazu der Cockney-Akzent: Gro\u00dfartig. Na denn, viel Spa\u00df.\u201c<\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Drau\u00dfen auf der Stra\u00dfe fiel mir auf, dass ich nirgends ein t\u00fcrkisches oder arabisches Gesicht sehen konnte. Die L\u00e4den waren alle \u2013 wie das \u201eVideodrom\u201c \u2013 f\u00fcr Leute wie mich gemacht: exklusive Schuhe, individuell gebaute M\u00f6bel, \u00d6ko-Eis und Fairtrade-Kaffee, ein Edelgrieche, spanische Weine, Schaukelpferde, Kochkurse, Kriminalromane. Blonde Kinder hatten den B\u00fcrgersteig in Beschlag genommen, und man sprach auf der Stra\u00dfe gr\u00f6\u00dftenteils Englisch. Aus dem Kiez war unversehens Prenzlauer Berg geworden, wo es so blond und kinderfreundlich zugeht wie bei Astrid Lindgren in ihren schlechteren B\u00fcchern.<\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">F\u00fcr kurze Zeit habe ich mich gefragt, ob die Gegner der Gentrifzierung nicht Recht haben. Ob man das Kippen eines ehedem Bezirks vom Abenteuerspielplatz ins Puppenh\u00e4usliche nicht gesetzlich aufhalten sollte.<\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Und doch wei\u00df ich, dass man eine Stadt, einen Stadtteil, einen Kiez, einen Zustand nicht einfrieren kann.\u00a0 Schon der Bezirk, der uns als Sch\u00fcler und Studenten in den 1960er Jahren anzog, war nicht der Bezirk, den ein kommunistischer Schriftsteller wie Walter Sch\u00f6nstedt in seinem Roman \u201eK\u00e4mpfende Jugend\u201c eher glorifizierte denn beschrieb, und in dem mein Nazi-Schwiegervater als Sozialbeamter arbeitete. Krieg und Mauerbau, der Wegzug der Arbeiter in die neuen Siedlungen am Stadtrand, die planm\u00e4\u00dfige Entmietung im Hinblick auf den vom Senat anvisierten Abriss und die Planierung f\u00fcr den Autobahnbau, der Zuzug von \u201eGastarbeitern\u201c und Studenten hatten aus dem ehedem proletarischen Bezirk einen Deklassierten-Stadtteil gemacht und zugleich die Grundlage gelegt f\u00fcr die sp\u00e4tere Gentrifizierung. Gerade die antib\u00fcrgerlichen Besetzer haben mit dem Erhalt der alten H\u00e4user und der Verhinderung der autogerechten Stadtplanung daf\u00fcr gesorgt, dass der Bezirk heute so anziehend wirkt auf Bildungs- und andere B\u00fcrger aus aller Welt.\u00a0 <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Ich versp\u00fcre auch keine Sentimentalit\u00e4t nach den Braunkohle\u00f6fen mit ihrem Schwefelgeruch, den kalten Klos auf halber Treppe, den br\u00f6ckelnden grauen Fassaden und undichten D\u00e4chern der Zeit, als ich in Kreuzberg wohnte; nach dem aggressiven Gegr\u00f6le der verbliebenen und verbitterten Proleten von ihren Balkonen herunter, wenn wir dort demonstrierten; nach der r\u00fcckw\u00e4rtsgewandten Revolutionsromantik der Zeit, als eine Band mit einem Namen wie \u201eLokomotive Kreuzberg\u201c re\u00fcssieren konnte; und auch nicht nach dem verkommenen Charme der besetzten H\u00e4user mit ihren aggressiven Funktion\u00e4ren und ihrer ach so b\u00fcrgerlichen, zur Schau getragenen antib\u00fcrgerlichen Attit\u00fcde; f\u00fcr die Hoch-Zeit des Punk im SO 36 war ich schon zu alt; und was die Romantik des Aussteigens angeht, so geht es mir wie meinem alten Freund K., der schon immer in Kreuzberg wohnt, als pensionierter Lehrer in einer Buchhandlung aushilft und sich \u00fcber die Gentrifizierung freut, nicht nur, weil das von ihm und einigen Freunden vor 30 Jahren gekaufte HausHoch-Zeit \u00a0nun ungef\u00e4hr zehnmal so viel wert ist wie damals: \u201eErstens kaufen die Leute B\u00fccher, und zweitens ist es ganz angenehm, wenn man morgens Br\u00f6tchen holen geht, nicht \u00fcber Junkie-Leichen steigen zu m\u00fcssen.\u201c <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Und schlie\u00dflich: Es ist ja nicht so, dass ganz Kreuzberg so geworden w\u00e4re wie die Touristenmeile rund um den Bergmannkiez. Wer die ber\u00fchmte \u201eKreuzberger Mischung\u201c genie\u00dfen will, das T\u00fcrkisch-Deutsche, Proletarisch-B\u00fcrgerliche Punkig-Sentimentale, der findet es ja noch auf der Oranienstra\u00dfe und im Kiez rund um den Kotti. Und diese Mischung dehnt sich ja aus in dem Ma\u00dfe, wie Nordneuk\u00f6lln (\u201eKreuzk\u00f6lln\u201c) und der Wedding entdeckt werden von Leuten, die sich die Mieten im hippen Kreuzberg nicht leisten k\u00f6nnen oder wollen. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Deshalb, und obwohl es mir ein wenig weh ums Herz ist: Nostalgie ist kein Grund, die Gentrifizierung aufzuhalten. F\u00fcr die Kinder, die auf der Fidicinstra\u00dfe unbeschwert spielen, wo Untergangspropheten noch vor zehn Jahren wegen der Herrschaft arabischer Jugendgangs und des Wegzugs der Wei\u00dfen nach Prenzelberg das Abkippen des Stadtteils an die Wand malten, wird Kreuzberg der Stadtteil sonniger Erinnerungen bleiben. Wer wirklich die soziale Durchmischung der Stadt will, wer die Entstehung von Ghettos verhindern m\u00f6chte, der kann nicht versuchen, den Status Quo einzufrieren, wie es die SPD und die Gr\u00fcnen versuchen. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Die SPD, indem sie zum Beispiel bei Neuvermietungen eine Mietsteigerungsgrenze von zehn Prozent gesetzlich festlegen und die Verwendung von Wohnraum als Ferienwohnungen verbieten will; die Gr\u00fcnen, indem sie \u201eLuxussanierungen\u201c genehmigungspflichtig machen (und das hei\u00dft in der Regel: verbieten) will. Man sagt, solche Ma\u00dfnahmen sollen die Verdr\u00e4ngung der alteingesessenen und \u00e4rmeren Bewohner aufhalten. Aber in Wirklichkeit geht es vor allem darum, den Neuzuzug anderer und wohlhabender B\u00fcrger zu verhindern. Es geht um den Klassenkampf nach oben, und zwar zum Erhalt der Privilegien derjenigen, die vom problematischen Ruf und vom subproletarischen Charakter eins Bezirks profitieren: Mittelschichtleute, die billige Mieten und ein multikulturelles Wohnfeld genie\u00dfen, w\u00e4hrend sie ihre Kinder in Privatschulen au\u00dferhalb des Bezirks schicken; Sozialarbeiter, die sich im Elend gut eingerichtet haben und die heimlichen Hauptnutznie\u00dfer der Sozialeinrichtungen und Sonderhilfsmittel sind. Und um die Parteien, die diesem Elend und diesem Klientel ihre Macht verdanken. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Ein Heinz Buschkowksky macht eine Medien-Karriere aus seinem \u201eProblembezirk\u201c Neuk\u00f6lln, der angeblich \u201e\u00fcberall\u201c sei, und seine Parteifreunde wollen verhindern, dass Studenten, K\u00fcnstler, Bohemiens, Kneipiers usw., gefolgt von Investoren, Bildungsb\u00fcrgern und Touristen, aus dem Problem- ein Vorzeigebezirk machen, in dem ein Buschkowsky seinen Ruf als mutigen Wahr-Sager verlieren w\u00fcrde. <\/span><\/p>\n<p><span style=\"color: black;font-family: Cambria;font-size: medium\">Berlin sei dazu verdammt, ewig zu werden und niemals zu sein, schrieb Karl Scheffler 1910.\u00a0 Das ist heute so wahr wie damals. Und das ist \u2013 trotz Bergmannkiez und Prenzelberg \u2013 gut so. <\/span><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" style=\"display:none\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F04%2F23%2Fneulich-in-kreuzberg%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F04%2F23%2Fneulich-in-kreuzberg%2F&text=Neulich%20in%20Kreuzberg&via=starkemeinungen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F04%2F23%2Fneulich-in-kreuzberg%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#0077b5\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0077b5\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0077b5\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F04%2F23%2Fneulich-in-kreuzberg%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#126567\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#126567\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#126567\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F04%2F23%2Fneulich-in-kreuzberg%2F%20Neulich%20in%20Kreuzberg\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#34af23\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#34af23\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#34af23\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Wie die meisten Gro\u00dfstadtbewohner kenne ich meine Stadt nicht wirklich. Mein allt\u00e4gliches Leben spielt sich ab zwischen meinem Wohnquartier im gutb\u00fcrgerlichen S\u00fcdwesten der Stadt, meinem Arbeitsplatz an der Grenze Kreuzberg und Mitte, der Wohnung meiner Tochter in der N\u00e4he des Kottbusser Tors in Kreuzberg, und den diversen Kinos, Museen, Galerien, Caf\u00e9s und Restaurants, haupts\u00e4chlich in Charlottenburg, Mitte und Kreuzberg, in&#8230; <a href=\"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/\">Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209,1],"tags":[459,1837],"class_list":["post-3871","post","type-post","status-publish","format-standard","hentry","category-alan-posener","category-allgemein","tag-berlin","tag-kreuzberg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neulich in Kreuzberg - starke-meinungen.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neulich in Kreuzberg - starke-meinungen.de\" \/>\n<meta property=\"og:description\" content=\"Wie die meisten Gro\u00dfstadtbewohner kenne ich meine Stadt nicht wirklich. Mein allt\u00e4gliches Leben spielt sich ab zwischen meinem Wohnquartier im gutb\u00fcrgerlichen S\u00fcdwesten der Stadt, meinem Arbeitsplatz an der Grenze Kreuzberg und Mitte, der Wohnung meiner Tochter in der N\u00e4he des Kottbusser Tors in Kreuzberg, und den diversen Kinos, Museen, Galerien, Caf\u00e9s und Restaurants, haupts\u00e4chlich in Charlottenburg, Mitte und Kreuzberg, in... Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/\" \/>\n<meta property=\"og:site_name\" content=\"starke-meinungen.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/starkemeinungen\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-22T23:52:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alan Posener\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:site\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alan Posener\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/\"},\"author\":{\"name\":\"Alan Posener\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/32d0faef7c31a37c1c89be993d7a6d28\"},\"headline\":\"Neulich in Kreuzberg\",\"datePublished\":\"2013-04-22T23:52:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/\"},\"wordCount\":1700,\"commentCount\":89,\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"keywords\":[\"Berlin\",\"Kreuzberg\"],\"articleSection\":[\"Alan Posener\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/\",\"name\":\"Neulich in Kreuzberg - starke-meinungen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\"},\"datePublished\":\"2013-04-22T23:52:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/04\\\/23\\\/neulich-in-kreuzberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neulich in Kreuzberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"name\":\"starke-meinungen.de\",\"description\":\"Autoren-Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\",\"name\":\"starke-meinungen.de\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"contentUrl\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"width\":1200,\"height\":630,\"caption\":\"starke-meinungen.de\"},\"image\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/starkemeinungen\\\/\",\"https:\\\/\\\/x.com\\\/starkemeinungen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/32d0faef7c31a37c1c89be993d7a6d28\",\"name\":\"Alan Posener\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"caption\":\"Alan Posener\"},\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/author\\\/posener\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neulich in Kreuzberg - starke-meinungen.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/","og_locale":"de_DE","og_type":"article","og_title":"Neulich in Kreuzberg - starke-meinungen.de","og_description":"Wie die meisten Gro\u00dfstadtbewohner kenne ich meine Stadt nicht wirklich. Mein allt\u00e4gliches Leben spielt sich ab zwischen meinem Wohnquartier im gutb\u00fcrgerlichen S\u00fcdwesten der Stadt, meinem Arbeitsplatz an der Grenze Kreuzberg und Mitte, der Wohnung meiner Tochter in der N\u00e4he des Kottbusser Tors in Kreuzberg, und den diversen Kinos, Museen, Galerien, Caf\u00e9s und Restaurants, haupts\u00e4chlich in Charlottenburg, Mitte und Kreuzberg, in... Weiterlesen &raquo;","og_url":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/","og_site_name":"starke-meinungen.de","article_publisher":"https:\/\/www.facebook.com\/starkemeinungen\/","article_published_time":"2013-04-22T23:52:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","type":"image\/jpeg"}],"author":"Alan Posener","twitter_card":"summary_large_image","twitter_creator":"@starkemeinungen","twitter_site":"@starkemeinungen","twitter_misc":{"Verfasst von":"Alan Posener","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/#article","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/"},"author":{"name":"Alan Posener","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/32d0faef7c31a37c1c89be993d7a6d28"},"headline":"Neulich in Kreuzberg","datePublished":"2013-04-22T23:52:09+00:00","mainEntityOfPage":{"@id":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/"},"wordCount":1700,"commentCount":89,"publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"keywords":["Berlin","Kreuzberg"],"articleSection":["Alan Posener"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/","url":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/","name":"Neulich in Kreuzberg - starke-meinungen.de","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/#website"},"datePublished":"2013-04-22T23:52:09+00:00","breadcrumb":{"@id":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/starke-meinungen.de\/blog\/2013\/04\/23\/neulich-in-kreuzberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/starke-meinungen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Neulich in Kreuzberg"}]},{"@type":"WebSite","@id":"https:\/\/starke-meinungen.de\/blog\/#website","url":"https:\/\/starke-meinungen.de\/blog\/","name":"starke-meinungen.de","description":"Autoren-Blog","publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/starke-meinungen.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/starke-meinungen.de\/blog\/#organization","name":"starke-meinungen.de","url":"https:\/\/starke-meinungen.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","contentUrl":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","width":1200,"height":630,"caption":"starke-meinungen.de"},"image":{"@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/starkemeinungen\/","https:\/\/x.com\/starkemeinungen"]},{"@type":"Person","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/32d0faef7c31a37c1c89be993d7a6d28","name":"Alan Posener","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","caption":"Alan Posener"},"url":"https:\/\/starke-meinungen.de\/blog\/author\/posener\/"}]}},"_links":{"self":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/comments?post=3871"}],"version-history":[{"count":2,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3871\/revisions"}],"predecessor-version":[{"id":3873,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3871\/revisions\/3873"}],"wp:attachment":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/media?parent=3871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/categories?post=3871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/tags?post=3871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}