

{"id":3831,"date":"2013-03-19T16:13:29","date_gmt":"2013-03-19T15:13:29","guid":{"rendered":"https:\/\/starke-meinungen.de\/blog\/?p=3831"},"modified":"2013-03-19T12:15:44","modified_gmt":"2013-03-19T11:15:44","slug":"angriff-von-rechts","status":"publish","type":"post","link":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/","title":{"rendered":"Angriff von rechts"},"content":{"rendered":"<p><strong>Von Adrian Zielcke:<\/strong><\/p>\n<p>Wir leben auf einer Insel der Seligen. Deutschland zieht den Rest Europas. Es geht ja bei weitem nicht nur um so kleine L\u00e4nder wie Griechenland und Zypern. Italien ist \u00fcberschuldet und in weiten Teilen weltweit nicht konkurrenzf\u00e4hig.<\/p>\n<p>Seit 150 Jahren pumpt der reiche Norden des Stiefels Geld in den S\u00fcden. Der Erfolg ist gleich Null. Spanien ist pleite, Portugal ebenso. Gro\u00dfbritannien ist entindustrialisiert, die Londoner City bringt Geld in das Land, die Banken sind Englands Ungl\u00fcck. Denn diese verhindern zusammen \u00a0mit der New Yorker Wall Street die notwendige Regelung des entfesselten Kapitalismus. <!--more-->Margret Thatcher und Ronald Reagan haben die althergebrachte Bankenordnung zerst\u00f6rt und damit letztendlich die Frage provoziert, wer eigentlich den Westen beherrscht: das Kapital oder die demokratischen Staaten. Frankreichs Industrie ist gro\u00dfenteils in einem jammerw\u00fcrdigen Zustand. Wer kauft noch franz\u00f6sische Autos? Das Ansehen von Pr\u00e4sident Hollande erreicht immer neue Tiefstwerte.<\/p>\n<p>Zu Recht. Denn der Pr\u00e4sident \u00a0tut immer noch so, als k\u00f6nne er die Krise der franz\u00f6sischen Industrie, den Verlust immer weiterer Arbeitspl\u00e4tze mit einer Politik der ruhigen Hand beherrschen. Kann er aber nicht.\u00a0 Vom Osten Europas und dem Balkan wollen wir lieber schweigen. Lediglich Polen, Tschechien und die Slowakei haben den Weg in die Gegenwart gefunden.<\/p>\n<p>Wohin f\u00fchrt das alles? Was wird aus Europa, wenn Millionen Menschen keine Aussicht haben, jemals einen guten Arbeitsplatz zu erhalten, der sie und ihre Familie ern\u00e4hrt?<\/p>\n<p>Und\u00a0 wir? Wir jammern, wir n\u00f6rgeln, wir sind unzufrieden. Wir haben zwar sichere Arbeitspl\u00e4tze, hervorragend aufgestellte Unternehmen, wir bauen die besten Maschinen und die besten Autos, die Gott sei Dank alle Welt haben will. Aber zufrieden sind wir nicht.<\/p>\n<p>Einige unzufriedene Zeitgenossen haben jetzt ein Ventil gefunden, sie haben eine neue Partei gegr\u00fcndet. Dagegen ist nichts zu sagen. Aber die ,,Alternative f\u00fcr Deutschland\u201c, die bei der Bundestagswahl in allen Wahlkreisen antreten will, sch\u00f6pft in tr\u00fcben Gew\u00e4ssern.<\/p>\n<p>Ihre Mitglieder sind zumeist \u00e4ltere Herren, Wissenschaftler, Journalisten, Unternehmer. Sie tr\u00e4umen nicht von einer guten Zukunft, sondern vom Weg zur\u00fcck in die gute, alte Zeit, als die D-Mark noch eine der besten W\u00e4hrungen \u00a0war, und \u00fcberhaupt die ganze Welt noch in Ordnung war. Die Konsequenz: ,,Deutschland muss sich ein Austrittsrecht aus der Eurozone erzwingen\u201c, hei\u00dft es im Wahlprogramm.<\/p>\n<p>Man stelle sich einen Moment vor, die Initiative h\u00e4tte Erfolg, Deutschland verl\u00e4sst die Eurozone und f\u00fchrt die D-Mark wieder ein. Was w\u00e4re die Folge? Alle Welt w\u00fcrde sich auf die D-Mark st\u00fcrzen, der Kurs w\u00fcrde in schwindelerregende H\u00f6hen steigen, der Rest-Euro w\u00fcrde fallen und fallen: In Europa k\u00f6nnte kaum jemand noch deutsche Produkte kaufen, die deutsche Industrie w\u00e4re der chinesischen Herausforderung nicht mehr gewachsen, weil ihre Produkte zu teuer w\u00fcrden.<\/p>\n<p>Dennoch ist die Sehnsucht nach der guten, alten Zeit lebendig, ja sie w\u00e4chst. Thilo Sarrazin hat mit seinem Buch,, Deutschland schafft sich ab\u201c, schon einmal vorgemacht, wohin uns rechte Populisten bringen k\u00f6nnen. Die Salafisten spielen den Islam-Hassern in die Hand.<\/p>\n<p>In vielen europ\u00e4ischen L\u00e4ndern gibt es inzwischen fremdenfeindliche Parteien, hier Gott sei Dank noch nicht. Aber das Potenzial f\u00fcr rechte Verf\u00fchrer ist riesig. In westdeutschen Gro\u00dfst\u00e4dten sind oftmals rund 50 Prozent und mehr der Grundsch\u00fcler aus Migrantenfamilien. Aus dem Osten str\u00f6men Roma und Sinti ein. \u00dcber den Mittelmeerraum kommen \u00fcber Griechenland Fl\u00fcchtlinge aus aller Welt in das vermeintliche Paradies Deutschland.<\/p>\n<p>Wenn das kein Stoff f\u00fcr Rechtspopulisten ist! Wir haben keinen J\u00f6rg Haider. Wir haben eine besonnene Kanzlerin, die genauso durch den Nebel der Eurokrise watet wie wir alle. Es gibt kein Lehrbuch f\u00fcr diese Krise. Aber wenn Europa nicht zusammenh\u00e4lt, dann geht mehr in die Br\u00fcche als der Euro.<\/p>\n<p>Angela Merkel bringt mit ruhiger Stimme Europa auf den Kurs: Weg vom Schuldenmachen, hin zu solider Finanzpolitik. Das bringt nach innen und nach au\u00dfen H\u00e4rten mit sich. Aber der Weg zur\u00fcck ist keine Alternative. Die ,,Alternative f\u00fcr Deutschland\u201c kann jedenfalls f\u00fcr die Kanzlerin gef\u00e4hrlicher werden als es der merkw\u00fcrdige Kanzlerkandidat der SPD ist.<\/p>\n<p><em>Adrian Zielcke war von 1970 bis 2010 Redaktionsmitglied der Stuttgarter Zeitung, davon die letzten zwanzig Jahre als Ressortleiter Au\u00dfenpolitik. Jetzt arbeitet er als freier Autor und freier Journalist.<\/em><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" style=\"display:none\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F03%2F19%2Fangriff-von-rechts%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F03%2F19%2Fangriff-von-rechts%2F&text=Angriff%20von%20rechts&via=starkemeinungen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F03%2F19%2Fangriff-von-rechts%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#0077b5\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0077b5\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0077b5\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F03%2F19%2Fangriff-von-rechts%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#126567\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#126567\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#126567\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2013%2F03%2F19%2Fangriff-von-rechts%2F%20Angriff%20von%20rechts\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#34af23\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#34af23\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#34af23\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Von Adrian Zielcke: Wir leben auf einer Insel der Seligen. Deutschland zieht den Rest Europas. Es geht ja bei weitem nicht nur um so kleine L\u00e4nder wie Griechenland und Zypern. Italien ist \u00fcberschuldet und in weiten Teilen weltweit nicht konkurrenzf\u00e4hig. Seit 150 Jahren pumpt der reiche Norden des Stiefels Geld in den S\u00fcden. Der Erfolg ist gleich Null. Spanien ist&#8230; <a href=\"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/\">Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,629],"tags":[2215,2214],"class_list":["post-3831","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-gastautor","tag-bankenrettung","tag-zypern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Angriff von rechts - starke-meinungen.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angriff von rechts - starke-meinungen.de\" \/>\n<meta property=\"og:description\" content=\"Von Adrian Zielcke: Wir leben auf einer Insel der Seligen. Deutschland zieht den Rest Europas. Es geht ja bei weitem nicht nur um so kleine L\u00e4nder wie Griechenland und Zypern. Italien ist \u00fcberschuldet und in weiten Teilen weltweit nicht konkurrenzf\u00e4hig. Seit 150 Jahren pumpt der reiche Norden des Stiefels Geld in den S\u00fcden. Der Erfolg ist gleich Null. Spanien ist... Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/\" \/>\n<meta property=\"og:site_name\" content=\"starke-meinungen.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/starkemeinungen\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-19T15:13:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gastautor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:site\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gastautor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/\"},\"author\":{\"name\":\"Gastautor\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/a03e0a730dd4d63894dcc16cdbaa6b64\"},\"headline\":\"Angriff von rechts\",\"datePublished\":\"2013-03-19T15:13:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/\"},\"wordCount\":722,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"keywords\":[\"Bankenrettung\",\"Zypern\"],\"articleSection\":{\"1\":\"Gastautor\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/\",\"name\":\"Angriff von rechts - starke-meinungen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\"},\"datePublished\":\"2013-03-19T15:13:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2013\\\/03\\\/19\\\/angriff-von-rechts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angriff von rechts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"name\":\"starke-meinungen.de\",\"description\":\"Autoren-Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\",\"name\":\"starke-meinungen.de\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"contentUrl\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"width\":1200,\"height\":630,\"caption\":\"starke-meinungen.de\"},\"image\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/starkemeinungen\\\/\",\"https:\\\/\\\/x.com\\\/starkemeinungen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/a03e0a730dd4d63894dcc16cdbaa6b64\",\"name\":\"Gastautor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8759fb61d9b27c08334d4e02d0a8ea6eb0fc0c3602cd7c3e58c0c89a6adba588?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8759fb61d9b27c08334d4e02d0a8ea6eb0fc0c3602cd7c3e58c0c89a6adba588?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8759fb61d9b27c08334d4e02d0a8ea6eb0fc0c3602cd7c3e58c0c89a6adba588?s=96&d=mm&r=g\",\"caption\":\"Gastautor\"},\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/author\\\/gastautor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angriff von rechts - starke-meinungen.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/","og_locale":"de_DE","og_type":"article","og_title":"Angriff von rechts - starke-meinungen.de","og_description":"Von Adrian Zielcke: Wir leben auf einer Insel der Seligen. Deutschland zieht den Rest Europas. Es geht ja bei weitem nicht nur um so kleine L\u00e4nder wie Griechenland und Zypern. Italien ist \u00fcberschuldet und in weiten Teilen weltweit nicht konkurrenzf\u00e4hig. Seit 150 Jahren pumpt der reiche Norden des Stiefels Geld in den S\u00fcden. Der Erfolg ist gleich Null. Spanien ist... Weiterlesen &raquo;","og_url":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/","og_site_name":"starke-meinungen.de","article_publisher":"https:\/\/www.facebook.com\/starkemeinungen\/","article_published_time":"2013-03-19T15:13:29+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","type":"image\/jpeg"}],"author":"Gastautor","twitter_card":"summary_large_image","twitter_creator":"@starkemeinungen","twitter_site":"@starkemeinungen","twitter_misc":{"Verfasst von":"Gastautor","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/#article","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/"},"author":{"name":"Gastautor","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/a03e0a730dd4d63894dcc16cdbaa6b64"},"headline":"Angriff von rechts","datePublished":"2013-03-19T15:13:29+00:00","mainEntityOfPage":{"@id":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/"},"wordCount":722,"commentCount":12,"publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"keywords":["Bankenrettung","Zypern"],"articleSection":{"1":"Gastautor"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/","url":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/","name":"Angriff von rechts - starke-meinungen.de","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/#website"},"datePublished":"2013-03-19T15:13:29+00:00","breadcrumb":{"@id":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/starke-meinungen.de\/blog\/2013\/03\/19\/angriff-von-rechts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/starke-meinungen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Angriff von rechts"}]},{"@type":"WebSite","@id":"https:\/\/starke-meinungen.de\/blog\/#website","url":"https:\/\/starke-meinungen.de\/blog\/","name":"starke-meinungen.de","description":"Autoren-Blog","publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/starke-meinungen.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/starke-meinungen.de\/blog\/#organization","name":"starke-meinungen.de","url":"https:\/\/starke-meinungen.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","contentUrl":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","width":1200,"height":630,"caption":"starke-meinungen.de"},"image":{"@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/starkemeinungen\/","https:\/\/x.com\/starkemeinungen"]},{"@type":"Person","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/a03e0a730dd4d63894dcc16cdbaa6b64","name":"Gastautor","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8759fb61d9b27c08334d4e02d0a8ea6eb0fc0c3602cd7c3e58c0c89a6adba588?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8759fb61d9b27c08334d4e02d0a8ea6eb0fc0c3602cd7c3e58c0c89a6adba588?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8759fb61d9b27c08334d4e02d0a8ea6eb0fc0c3602cd7c3e58c0c89a6adba588?s=96&d=mm&r=g","caption":"Gastautor"},"url":"https:\/\/starke-meinungen.de\/blog\/author\/gastautor\/"}]}},"_links":{"self":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/comments?post=3831"}],"version-history":[{"count":3,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3831\/revisions"}],"predecessor-version":[{"id":3833,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3831\/revisions\/3833"}],"wp:attachment":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/media?parent=3831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/categories?post=3831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/tags?post=3831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}