

{"id":3334,"date":"2012-05-22T00:52:47","date_gmt":"2012-05-21T23:52:47","guid":{"rendered":"https:\/\/starke-meinungen.de\/blog\/?p=3334"},"modified":"2012-05-21T09:53:33","modified_gmt":"2012-05-21T08:53:33","slug":"fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau","status":"publish","type":"post","link":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/","title":{"rendered":"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau."},"content":{"rendered":"<p><span style=\"font-family: Times New Roman;font-size: small\">\u00dcber den neuen \u201eGro\u00df\u201cFlughafen Berlins l\u00e4sst sich viel Negatives sagen, beginnend mit der \u00a0Anwohnert\u00e4uschung hinsichtlich der An- und Abflugrouten und dem v\u00f6lligen Versagen des so genannten \u201eAufsichtsrats\u201c (und damit sind wir erst beim Buchstaben \u201eA\u201c). Wenige Tage, bevor jener Augen-zu-und-durch-Rat die Verschiebung der Er\u00f6ffnung bekannt gab, habe ich die \u00a0Baustelle besucht, und es war selbst einem Laien wie mir klar, dass der Termin nicht zu halten sein w\u00fcrde. Nach der Er\u00f6ffnung im M\u00e4rz 2013 d\u00fcrfte ziemlich schnell klar werden, dass der neue Flughafen schon jetzt zu klein ist und dass insbesondere die zentrale Check-in-Halle f\u00fcrs Chaos vorprogrammiert ist. <\/span><\/p>\n<p><em><span style=\"font-family: Times New Roman;font-size: small\">You read it here first.<\/span><\/em><\/p>\n<p><span style=\"font-family: Times New Roman;font-size: small\">Eine Sache aber haben Gerkan, Marg und Partner in BER richtig gemacht, und zwar bei den Billig-Airlines Easyjet, Germanwings und Co., und auf deren ausdr\u00fccklichen Wunsch hin: Es gibt keine Fluggastbr\u00fccken.<!--more--> Man l\u00e4uft vom Terminal zum Flugzeug und betritt die Maschine \u00fcber Treppen vorn und hinten. Das ist ein gro\u00dfer Fortschritt, und ich verstehe nicht, weshalb die anderen Fluggesellschaften diesem Beispiel nicht folgen.<\/span><\/p>\n<p><span style=\"font-family: Times New Roman;font-size: small\">Ein Flugzeug ist im Wesentlichen eine fliegende Metallr\u00f6hre. Wenn sie nur von vorn gef\u00fcllt wird, kommt es zu Staus. Jeder, der geflogen ist, wei\u00df davon zu berichten. Man steht an, um die Bordkarte vorzuzeigen, man steht in der Fluggastbr\u00fccke, man steht im Flugzeuggang. Die Fluggesellschaften k\u00f6nnen noch so oft die Leute auffordern, die Passagiere in den hinteren Sitzreihen zuerst einsteigen zu lassen, es reicht, wenn f\u00fcnf oder sechs Egoisten oder Schwerh\u00f6rige sich nicht daran halten, um alle anderen aufzuhalten. Ein cleveres Boarding-System m\u00fcsste au\u00dferdem daf\u00fcr sorgen, dass zuerst Passagiere mit Fensterplatz einsteigen, wodurch das umst\u00e4ndliche Aufstehen, um dem \u2013 immer! \u2013 sp\u00e4ter kommenden Fensterplatzbesitzer hineinzulassen, wodurch wieder der Gang blockiert wird, vermieden werden k\u00f6nnte. Aber je ausgekl\u00fcgelter ein System ist, desto weniger funktioniert es in der Praxis. Nach meiner Erfahrung macht es Easyjet am besten. Wer etwas mehr bezahlt, oder kleine Kinder dabei hat oder behindert ist, darf zuerst einsteigen. Danach wird das Flugzeug \u00fcber die beiden T\u00fcren vorn und hinten bestiegen, und die Leute k\u00f6nnen sich ihre Pl\u00e4tze selbst aussuchen. Die Schwarmintelligenz funktioniert. <\/span><\/p>\n<p><span style=\"font-family: Times New Roman;font-size: small\">Idealerweise w\u00fcrden gr\u00f6\u00dfere Flugzeuge sogar nicht nur zwei, sondern drei oder vier T\u00fcren haben, also auch zwei in der Mitte, durch die Leute mit entsprechenden Sitzpl\u00e4tzen die Maschine besteigen und verlassen. Offensichtlich \u00fcbersteigt es die Fantasie moderner Ingenieure, entsprechende Fluggastbr\u00fccken zu bauen. Aber die werden ohnehin nur gebraucht, wenn es mal regnet oder schneit. Das kommt, zugegeben, in unseren Breiten nicht selten vor. Doch da kann man die Treppen mit D\u00e4chern versehen und die Passagiere gegebenenfalls mit Bussen abholen \u2013 ansonsten eine weitere Flughafen-Unsitte, die zu weiterem Warten f\u00fchrt, als ob man nicht imstande w\u00e4re, die hundert Meter von der Parkposition zum Terminal zu laufen. <\/span><\/p>\n<p><span style=\"font-family: Times New Roman;font-size: small\">W\u00fcrde man ernsthaft \u00fcberlegen, wie Flugzeuge am schnellsten und f\u00fcr Flugg\u00e4ste und \u00a0Bordpersonal m\u00f6glichst stressfrei \u2013 auch bei Schnee und Regen \u2013 zu be- und entladen sind, w\u00fcrde man sich nicht nur \u2013 wie die Billigflieger in BER \u2013 auf die gute alte Gangway besinnen, sondern bei der Flughafenarchitektur noch weiter zur\u00fcckgehen und sich ein Beispiel am Flughafen Tempelhof nehmen. Dort hatten die Maschinen unter dem riesigen ausgekragtem Dach des Vorfelds Platz. Die Passagiere stiegen im trockenen ein und aus. F\u00fcr moderne Ingenieure d\u00fcrfte es ein Leichtes sein, D\u00e4cher zu bauen, unter denen auch Jumbo-Jets Platz finden, und die so konstruiert sind, dass weder L\u00e4rm noch Flugbenzinabgase ein Problem bilden. Man denke an Konstruktionen, wie sie Frei Otto f\u00fcr das M\u00fcnchener Olympia-Stadion entwarf. Freilich w\u00fcrde das verlangen, dass man sich wieder mehr dem Bed\u00fcrfnis der Passagiere zuwendet als dem Anliegen der Ladenbesitzer, die in jedem modernen Flughafen den L\u00f6wenanteil der Fl\u00e4che pachten und entsprechende Entw\u00fcrfe verlangen \u2013 im neuen Berliner Flughafen beispielsweise gibt es \u2013 wie im bisherigen Flughafen Sch\u00f6nefeld \u2013 keine M\u00f6glichkeit, von der Sicherheits\u00fcberpr\u00fcfung zum Flugsteig zu gelangen, ohne den Duty-Free-Shop zu passieren! <\/span><\/p>\n<p><span style=\"font-family: Times New Roman;font-size: small\">Den Fluggast ernst nehmen \u2013 als jemand, der fliegen will (oder muss), nicht shoppen und fressen, anstehen und wieder anstehen und wieder anstehen \u2013 w\u00fcrde bedeuten, beim Flughafenbau wieder so innovativ zu werden, wie es die Berliner Flugh\u00e4fen Tempelhof und Tegel zu ihrer Zeit waren. Gerkan, Marg und Partner haben in Tegel und beim Berliner Hauptbahnhof gezeigt, dass sie das k\u00f6nnen. Im neuen Flughafen durften sie wohl nicht. Schade.<\/span><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" style=\"display:none\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2012%2F05%2F22%2Ffliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2012%2F05%2F22%2Ffliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau%2F&text=Fliegen%2C%20nicht%20shoppen%2C%20fressen%20und%20anstehen.%20Gegen%20die%20Fantasielosigkeit%20beim%20Flughafenbau.&via=starkemeinungen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2012%2F05%2F22%2Ffliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#0077b5\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0077b5\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0077b5\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2012%2F05%2F22%2Ffliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#126567\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#126567\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#126567\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2012%2F05%2F22%2Ffliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau%2F%20Fliegen%2C%20nicht%20shoppen%2C%20fressen%20und%20anstehen.%20Gegen%20die%20Fantasielosigkeit%20beim%20Flughafenbau.\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#34af23\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#34af23\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#34af23\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00dcber den neuen \u201eGro\u00df\u201cFlughafen Berlins l\u00e4sst sich viel Negatives sagen, beginnend mit der \u00a0Anwohnert\u00e4uschung hinsichtlich der An- und Abflugrouten und dem v\u00f6lligen Versagen des so genannten \u201eAufsichtsrats\u201c (und damit sind wir erst beim Buchstaben \u201eA\u201c). Wenige Tage, bevor jener Augen-zu-und-durch-Rat die Verschiebung der Er\u00f6ffnung bekannt gab, habe ich die \u00a0Baustelle besucht, und es war selbst einem Laien wie mir klar,&#8230; <a href=\"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/\">Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209,1],"tags":[1725],"class_list":["post-3334","post","type-post","status-publish","format-standard","hentry","category-alan-posener","category-allgemein","tag-flughafen-berlin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau. - starke-meinungen.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau. - starke-meinungen.de\" \/>\n<meta property=\"og:description\" content=\"\u00dcber den neuen \u201eGro\u00df\u201cFlughafen Berlins l\u00e4sst sich viel Negatives sagen, beginnend mit der \u00a0Anwohnert\u00e4uschung hinsichtlich der An- und Abflugrouten und dem v\u00f6lligen Versagen des so genannten \u201eAufsichtsrats\u201c (und damit sind wir erst beim Buchstaben \u201eA\u201c). Wenige Tage, bevor jener Augen-zu-und-durch-Rat die Verschiebung der Er\u00f6ffnung bekannt gab, habe ich die \u00a0Baustelle besucht, und es war selbst einem Laien wie mir klar,... Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/\" \/>\n<meta property=\"og:site_name\" content=\"starke-meinungen.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/starkemeinungen\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-21T23:52:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alan Posener\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:site\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alan Posener\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/\"},\"author\":{\"name\":\"Alan Posener\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/32d0faef7c31a37c1c89be993d7a6d28\"},\"headline\":\"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau.\",\"datePublished\":\"2012-05-21T23:52:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/\"},\"wordCount\":759,\"commentCount\":43,\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"keywords\":[\"Flughafen Berlin\"],\"articleSection\":[\"Alan Posener\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/\",\"name\":\"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau. - starke-meinungen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\"},\"datePublished\":\"2012-05-21T23:52:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2012\\\/05\\\/22\\\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"name\":\"starke-meinungen.de\",\"description\":\"Autoren-Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\",\"name\":\"starke-meinungen.de\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"contentUrl\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"width\":1200,\"height\":630,\"caption\":\"starke-meinungen.de\"},\"image\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/starkemeinungen\\\/\",\"https:\\\/\\\/x.com\\\/starkemeinungen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/32d0faef7c31a37c1c89be993d7a6d28\",\"name\":\"Alan Posener\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"caption\":\"Alan Posener\"},\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/author\\\/posener\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau. - starke-meinungen.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/","og_locale":"de_DE","og_type":"article","og_title":"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau. - starke-meinungen.de","og_description":"\u00dcber den neuen \u201eGro\u00df\u201cFlughafen Berlins l\u00e4sst sich viel Negatives sagen, beginnend mit der \u00a0Anwohnert\u00e4uschung hinsichtlich der An- und Abflugrouten und dem v\u00f6lligen Versagen des so genannten \u201eAufsichtsrats\u201c (und damit sind wir erst beim Buchstaben \u201eA\u201c). Wenige Tage, bevor jener Augen-zu-und-durch-Rat die Verschiebung der Er\u00f6ffnung bekannt gab, habe ich die \u00a0Baustelle besucht, und es war selbst einem Laien wie mir klar,... Weiterlesen &raquo;","og_url":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/","og_site_name":"starke-meinungen.de","article_publisher":"https:\/\/www.facebook.com\/starkemeinungen\/","article_published_time":"2012-05-21T23:52:47+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","type":"image\/jpeg"}],"author":"Alan Posener","twitter_card":"summary_large_image","twitter_creator":"@starkemeinungen","twitter_site":"@starkemeinungen","twitter_misc":{"Verfasst von":"Alan Posener","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/#article","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/"},"author":{"name":"Alan Posener","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/32d0faef7c31a37c1c89be993d7a6d28"},"headline":"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau.","datePublished":"2012-05-21T23:52:47+00:00","mainEntityOfPage":{"@id":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/"},"wordCount":759,"commentCount":43,"publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"keywords":["Flughafen Berlin"],"articleSection":["Alan Posener"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/","url":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/","name":"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau. - starke-meinungen.de","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/#website"},"datePublished":"2012-05-21T23:52:47+00:00","breadcrumb":{"@id":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/starke-meinungen.de\/blog\/2012\/05\/22\/fliegen-nicht-shoppen-fressen-und-anstehen-gegen-die-fantasielosigkeit-beim-flughafenbau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/starke-meinungen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Fliegen, nicht shoppen, fressen und anstehen. Gegen die Fantasielosigkeit beim Flughafenbau."}]},{"@type":"WebSite","@id":"https:\/\/starke-meinungen.de\/blog\/#website","url":"https:\/\/starke-meinungen.de\/blog\/","name":"starke-meinungen.de","description":"Autoren-Blog","publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/starke-meinungen.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/starke-meinungen.de\/blog\/#organization","name":"starke-meinungen.de","url":"https:\/\/starke-meinungen.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","contentUrl":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","width":1200,"height":630,"caption":"starke-meinungen.de"},"image":{"@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/starkemeinungen\/","https:\/\/x.com\/starkemeinungen"]},{"@type":"Person","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/32d0faef7c31a37c1c89be993d7a6d28","name":"Alan Posener","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","caption":"Alan Posener"},"url":"https:\/\/starke-meinungen.de\/blog\/author\/posener\/"}]}},"_links":{"self":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/comments?post=3334"}],"version-history":[{"count":1,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3334\/revisions"}],"predecessor-version":[{"id":3335,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/3334\/revisions\/3335"}],"wp:attachment":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/media?parent=3334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/categories?post=3334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/tags?post=3334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}