

{"id":2701,"date":"2011-05-24T00:11:51","date_gmt":"2011-05-23T23:11:51","guid":{"rendered":"https:\/\/starke-meinungen.de\/blog\/?p=2701"},"modified":"2011-05-22T20:16:29","modified_gmt":"2011-05-22T19:16:29","slug":"warum-unsere-leitkultur-kapitalismusfeindlich-ist","status":"publish","type":"post","link":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/","title":{"rendered":"Warum unsere Leitkultur kapitalismusfeindlich ist"},"content":{"rendered":"<p>Warum, so fragte mich (und sich) neulich der kluge Gideon B\u00f6ss, lieben wir den Kapitalismus nicht? Es ist in der Tat nicht ohne weiteres zu verstehen.<\/p>\n<p>Dem Kapitalismus verdanken wir einen unerh\u00f6rten Wohlstand. Er war und ist in der Bundesrepublik Deutschland \u2013 viel mehr als Einigkeit, Recht und Freiheit \u2013 \u201edes Gl\u00fcckes Unterpfand\u201c.\u00a0 <!--more-->Er bildete die eigentliche Basis der Wiedervereinigung: \u201eWenn die D-Mark nicht zu uns kommt, kommen wir zur D-Mark\u201c, riefen die Ossis, was blieb Kohl also \u00fcbrig? Er war Bestandteil jener \u201eFdGO\u201c, auf die fr\u00fcher alle Lehrer bei Strafe des Berufsverbots verpflichtet wurden, weil sich die Verfassung \u00fcber die Wirtschaftsordnung der Bundesrepublik \u2013 und das ist symptomatisch \u2013 vornehm ausschweigt. Man lebt gern im Kapitalismus, sch\u00e4mt sich aber daf\u00fcr. Und r\u00e4cht sich f\u00fcr das Schamgef\u00fchl an der FDP. Aber das ist eine andere Frage.<\/p>\n<p>Die Frage war, warum wir den Kapitalismus nicht lieben.<\/p>\n<p>Klar, er ist ungerecht. Aber der Sozialismus ist noch ungerechter. Das Leben ist ungerecht.<\/p>\n<p>Klar, viele Kapitalisten und Manager sind Unsympathlinge. Ackermann. Strau\u00df-Kahn. Der merkw\u00fcrdige Typ, der im Fernsehen durch einen sprechenden Schimpansen seine \u201enur in Deutschland hergestellten\u201c Trikotagen anpreisen l\u00e4sst.\u00a0 Andererseits gibt es Bill Gates. Steve Jobs. George Soros. Und Lafontaine ist doch auch nicht gerade ein Sympathietr\u00e4ger.<\/p>\n<p>Klar, er ist irgendwie laut, unkultiviert, r\u00fccksichtslos. Aber das ist doch der Revolution\u00e4re Block auch.<\/p>\n<p>Klar, er ist prinzipienlos. Aber das sind wir alle.<\/p>\n<p>Vergessen wir diese Argumente. Es gibt ja auch bessere, zum Beispiel von Karl Marx. Aber ich habe das Gef\u00fchl, dass es beim Anti-Kapitalismus \u2013 wie bei jeder Phobie \u2013 nicht um Argumente geht. Zuerst ist die Abneigung da, dazu sucht man sich dann die passenden Argumente.<\/p>\n<p>Woher kommt diese Abneigung? Meines Erachtens ist er tief in unserer kulturellen DNA verankert. Unsere Leitkultur, sagt man, ist christlich, das Christentum hat uns \u201ehistorisch gepr\u00e4gt\u201c. Das stimmt wohl. Und das Christentum ist nun einmal in seinem Wesenskern antikapitalistisch, ja \u2013 <em>horribile dictu<\/em> \u2013 sozialistisch. In der\u00a0 Bergpredigt (Mt 5,1 ff) werden nicht nur die Armen f\u00fcr \u201eselig\u201c erkl\u00e4rt; Jesus fordert sogar zum Nichtstun auf \u2013 und hat ja seine Anh\u00e4nger von ihren ehrlichen Brotberufen, etwa als Fischer, weggelockt: \u201eDeswegen sage ich euch: Sorgt euch nicht um euer Leben und darum, dass ihr etwas zu essen habt, noch um euren Leib und darum, dass ir etwas anzuziehen habt. (\u2026) Seht euch die V\u00f6gel des Himmels an: Sie s\u00e4en nicht, sie ernten nicht und sammaeln keine Vorr\u00e4te in Scheunen, euer himmlischer Vater ern\u00e4hrt sie. (\u2026) Lernt von den Lilien, die auf dem Felde wachsen: Sie arbeiten nicht und spinnen nicht. Doch ich sage euch: Selbst Salomo war in all seiner Pracht nicht gekleidet wie eine von ihnen. (\u2026) Macht euch also keine Sorgen\u2026\u201c (Mt 6,25ff).<\/p>\n<p>Das klingt nach einem Pl\u00e4doyer f\u00fcr das bedingungslose Grundeinkommen. Anh\u00e4nger des Leistungsprinzips jedenfalls k\u00f6nnen sich kaum auf Jesus berufen \u2013 man lese das Gleichnis von den Arbeitern im Weinberg (Mt 20,1 \u2013 16). Und da gibt es schlie\u00dflich den bekannten Spruch: \u201eEher geht ein Kamel durch ein Nadel\u00f6hr, als dass ein Reicher in das Reich Gottes gelangt.\u201c (Mt 19,24) Zuvor hatte Jesus einem reichen Mann, der \u201ealle Gebote befolgt\u201c hatte, gesagt: \u201eWenn du vollkommen sein willst, geh, verkauf deinen Besitz und gib dein Geld den Armen; so wirst du einen bleibenden Schatz im Himmel haben\u2026\u201c Woraufhin der Mann \u201etraurig wegging, denn er hatte ein gro\u00dfes Verm\u00f6gen\u201c (Mt 19,20ff).<\/p>\n<p>Die Aussagen des Rabbi Jesus sind so eindeutig, dass man sich fragt, wie die Kirchen es bis heute schaffen, sie so ganz und gar zu ignorieren. Aber das ist nicht mein Thema. M\u00f6gen die Kirchen in der Praxis meistens auf der Seite des Reichtums und der Macht gestanden haben; gepredigt haben sie immer die W\u00fcrde der Armut, die Notwendigkeit sozialer Barmherzigkeit, den Fluch des Reichtums.<\/p>\n<p>Noch st\u00e4rker als das Wort wirkte durch die Jahrhunderte die Ikonographie des Christentums: der K\u00f6nig der Welt, geboren in einer Krippe, weil es in der Herberge keinen Platz f\u00fcr den Bautischler und seine schwangere Verlobte gibt. Wir m\u00f6gen, wie Papst Benedikt nicht m\u00fcde wird zu betonen, eine entchristlichte, neuheidnische Gesellschaft sein, auch als Folge des eklatanten Widerspruchs zwischen den Worten und den Taten der Christen, aber wir haben die Botschaft l\u00e4ngst internalisiert.<\/p>\n<p>Man mag einwenden, dass Max Weber in der protestantischen Ethik den Geist des Kapitalismus entdeckte; und dass die christlichste Nation dieser Erde, die USA, zugleich die kapitalistischste sei. Tats\u00e4chlich mag die protestantische \u201einnerweltliche Askese\u201c, wie es Weber nannte, der Kapitalakkumulation f\u00f6rderlich sein und sich mit solchen Passagen der Bibel wie den eben zitierten begr\u00fcnden lassen; der Arbeitsethos der Protestanten ist aber schlichtweg unchristlich.<\/p>\n<p>Was die USA betrifft, so bin ich keineswegs \u00fcberzeugt, wie man uns weismacht, dass man dort so viel kapitalismusfreundlicher ist als hier. Hollywood jedenfalls lebt von einem aggressiven Antikapitalismus, man denke an \u201eWall Street\u201c, \u201ePretty Woman\u201c, oder \u201eFamily Man\u201c, an Klassiker wie Charlie Chaplins \u201eModern Times\u201c oder Frank Capra\u2019s \u201eIt\u2019s A Wonderful Life\u201c. Es ist nur so, dass man dort noch staatsfeindlicher ist als hier.<\/p>\n<p>Sieht man hier Gewerkschaften und Staat als Gegner des Kapitals, so ist es dort eher das Kleinb\u00fcrgertum: Der kleine Ladenbesitzer, der Direktor der lokalen Bank, der ihm ohne Sicherheiten Geld leiht, weil er \u201eseinem Wort traut\u201c, der ehrliche Fabrikant \u2013 und der kleine Gauner. Das entspricht der Sozialstruktur und den Ambitionen derjenigen, die nach Amerika auswanderten, um ihr Gl\u00fcck zu suchen.<\/p>\n<p>Weil wir aber christlich gepr\u00e4gt bleiben \u2013 auch der Marxismus ist lediglich ein weltliches Evangelium \u2013 k\u00f6nnen wir den Kapitalismus nicht lieben. Wir genie\u00dfen ihn, wir m\u00f6chten ihn nicht missen, aber wir k\u00f6nnen ihn nicht lieben.<\/p>\n<p>\u00dcbrigens zeigt dieses Beispiel paradigmatisch, dass man nicht aus den heiligen Schriften einer Religion Schlussfolgerungen ziehen darf auf das tats\u00e4chliche Verhalten ihrer Anh\u00e4nger. Ich w\u00fcrde sogar behaupten, dass die Schizophrenie zwischen Leben und F\u00fchlen ein Grundzug zumindest des Christentums und des \u2013 ebenso kapitalismusfeindlichen \u2013 Islam ist.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left shariff-buttonstretch\" style=\"display:none\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2011%2F05%2F24%2Fwarum-unsere-leitkultur-kapitalismusfeindlich-ist%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2011%2F05%2F24%2Fwarum-unsere-leitkultur-kapitalismusfeindlich-ist%2F&text=Warum%20unsere%20Leitkultur%20kapitalismusfeindlich%20ist&via=starkemeinungen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2011%2F05%2F24%2Fwarum-unsere-leitkultur-kapitalismusfeindlich-ist%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#0077b5\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0077b5\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0077b5\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2011%2F05%2F24%2Fwarum-unsere-leitkultur-kapitalismusfeindlich-ist%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#126567\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#126567\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#126567\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fstarke-meinungen.de%2Fblog%2F2011%2F05%2F24%2Fwarum-unsere-leitkultur-kapitalismusfeindlich-ist%2F%20Warum%20unsere%20Leitkultur%20kapitalismusfeindlich%20ist\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#34af23\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#34af23\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#34af23\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Warum, so fragte mich (und sich) neulich der kluge Gideon B\u00f6ss, lieben wir den Kapitalismus nicht? Es ist in der Tat nicht ohne weiteres zu verstehen. Dem Kapitalismus verdanken wir einen unerh\u00f6rten Wohlstand. Er war und ist in der Bundesrepublik Deutschland \u2013 viel mehr als Einigkeit, Recht und Freiheit \u2013 \u201edes Gl\u00fcckes Unterpfand\u201c.\u00a0<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[209,1],"tags":[1841,1840,168,199],"class_list":["post-2701","post","type-post","status-publish","format-standard","hentry","category-alan-posener","category-allgemein","tag-bergpredigt","tag-gideon-boss","tag-kapitalismus","tag-religion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warum unsere Leitkultur kapitalismusfeindlich ist - starke-meinungen.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warum unsere Leitkultur kapitalismusfeindlich ist - starke-meinungen.de\" \/>\n<meta property=\"og:description\" content=\"Warum, so fragte mich (und sich) neulich der kluge Gideon B\u00f6ss, lieben wir den Kapitalismus nicht? Es ist in der Tat nicht ohne weiteres zu verstehen. Dem Kapitalismus verdanken wir einen unerh\u00f6rten Wohlstand. Er war und ist in der Bundesrepublik Deutschland \u2013 viel mehr als Einigkeit, Recht und Freiheit \u2013 \u201edes Gl\u00fcckes Unterpfand\u201c.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/\" \/>\n<meta property=\"og:site_name\" content=\"starke-meinungen.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/starkemeinungen\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-23T23:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alan Posener\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:site\" content=\"@starkemeinungen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alan Posener\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/\"},\"author\":{\"name\":\"Alan Posener\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/32d0faef7c31a37c1c89be993d7a6d28\"},\"headline\":\"Warum unsere Leitkultur kapitalismusfeindlich ist\",\"datePublished\":\"2011-05-23T23:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/\"},\"wordCount\":1003,\"commentCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"keywords\":[\"Bergpredigt\",\"Gideon B\u00f6ss\",\"Kapitalismus\",\"Religion\"],\"articleSection\":[\"Alan Posener\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/\",\"name\":\"Warum unsere Leitkultur kapitalismusfeindlich ist - starke-meinungen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\"},\"datePublished\":\"2011-05-23T23:11:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/2011\\\/05\\\/24\\\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum unsere Leitkultur kapitalismusfeindlich ist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"name\":\"starke-meinungen.de\",\"description\":\"Autoren-Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#organization\",\"name\":\"starke-meinungen.de\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"contentUrl\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/wp-content\\\/uploads\\\/starke-meinungen-fb-header.jpg\",\"width\":1200,\"height\":630,\"caption\":\"starke-meinungen.de\"},\"image\":{\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/starkemeinungen\\\/\",\"https:\\\/\\\/x.com\\\/starkemeinungen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/#\\\/schema\\\/person\\\/32d0faef7c31a37c1c89be993d7a6d28\",\"name\":\"Alan Posener\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g\",\"caption\":\"Alan Posener\"},\"url\":\"https:\\\/\\\/starke-meinungen.de\\\/blog\\\/author\\\/posener\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warum unsere Leitkultur kapitalismusfeindlich ist - starke-meinungen.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/","og_locale":"de_DE","og_type":"article","og_title":"Warum unsere Leitkultur kapitalismusfeindlich ist - starke-meinungen.de","og_description":"Warum, so fragte mich (und sich) neulich der kluge Gideon B\u00f6ss, lieben wir den Kapitalismus nicht? Es ist in der Tat nicht ohne weiteres zu verstehen. Dem Kapitalismus verdanken wir einen unerh\u00f6rten Wohlstand. Er war und ist in der Bundesrepublik Deutschland \u2013 viel mehr als Einigkeit, Recht und Freiheit \u2013 \u201edes Gl\u00fcckes Unterpfand\u201c.\u00a0","og_url":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/","og_site_name":"starke-meinungen.de","article_publisher":"https:\/\/www.facebook.com\/starkemeinungen\/","article_published_time":"2011-05-23T23:11:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","type":"image\/jpeg"}],"author":"Alan Posener","twitter_card":"summary_large_image","twitter_creator":"@starkemeinungen","twitter_site":"@starkemeinungen","twitter_misc":{"Verfasst von":"Alan Posener","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/#article","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/"},"author":{"name":"Alan Posener","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/32d0faef7c31a37c1c89be993d7a6d28"},"headline":"Warum unsere Leitkultur kapitalismusfeindlich ist","datePublished":"2011-05-23T23:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/"},"wordCount":1003,"commentCount":30,"publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"keywords":["Bergpredigt","Gideon B\u00f6ss","Kapitalismus","Religion"],"articleSection":["Alan Posener"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/","url":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/","name":"Warum unsere Leitkultur kapitalismusfeindlich ist - starke-meinungen.de","isPartOf":{"@id":"https:\/\/starke-meinungen.de\/blog\/#website"},"datePublished":"2011-05-23T23:11:51+00:00","breadcrumb":{"@id":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/starke-meinungen.de\/blog\/2011\/05\/24\/warum-unsere-leitkultur-kapitalismusfeindlich-ist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/starke-meinungen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Warum unsere Leitkultur kapitalismusfeindlich ist"}]},{"@type":"WebSite","@id":"https:\/\/starke-meinungen.de\/blog\/#website","url":"https:\/\/starke-meinungen.de\/blog\/","name":"starke-meinungen.de","description":"Autoren-Blog","publisher":{"@id":"https:\/\/starke-meinungen.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/starke-meinungen.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/starke-meinungen.de\/blog\/#organization","name":"starke-meinungen.de","url":"https:\/\/starke-meinungen.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","contentUrl":"https:\/\/starke-meinungen.de\/blog\/wp-content\/uploads\/starke-meinungen-fb-header.jpg","width":1200,"height":630,"caption":"starke-meinungen.de"},"image":{"@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/starkemeinungen\/","https:\/\/x.com\/starkemeinungen"]},{"@type":"Person","@id":"https:\/\/starke-meinungen.de\/blog\/#\/schema\/person\/32d0faef7c31a37c1c89be993d7a6d28","name":"Alan Posener","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c75c8818a9ab78c4faa75048dba7844e2587998cda4d93f84e7d86f7e21a9b90?s=96&d=mm&r=g","caption":"Alan Posener"},"url":"https:\/\/starke-meinungen.de\/blog\/author\/posener\/"}]}},"_links":{"self":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":2,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/2701\/revisions"}],"predecessor-version":[{"id":2703,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/posts\/2701\/revisions\/2703"}],"wp:attachment":[{"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/categories?post=2701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/starke-meinungen.de\/blog\/wp-json\/wp\/v2\/tags?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}